{"id":415840,"date":"2026-09-01T07:30:02","date_gmt":"2026-09-01T07:30:02","guid":{"rendered":"https:\/\/occasions-teile.ch\/product\/vw-touran-bremszange-bremssattel-hinten-14\/"},"modified":"2026-09-01T07:30:08","modified_gmt":"2026-09-01T07:30:08","slug":"vw-touran-bremszange-bremssattel-hinten-14","status":"publish","type":"product","link":"https:\/\/occasions-teile.ch\/en\/produkt\/vw-touran-bremszange-bremssattel-hinten-14\/","title":{"rendered":"VW Touran  Bremszange Bremssattel hinten"},"content":{"rendered":"<p><span><b>Technische Daten<\/b><\/p>\n<p> Fahrzeug: VW Touran  1.4 TSI<br \/>\n Chassis Nr.: WVGZZZ1TZ8W076631<br \/>\n Baujahr: 2007<br \/>\n Kilometer: 232169 KM<br \/>\n Leistung: 140 KW<br \/>\n Hubraum: 1390 ccm<br \/>\n Typ: 1VD386<br \/>\n Farbcode: LeichtBraun<br \/>\n Hinweise: &#8211;<\/p>\n<p> Versand: Versand nur in der Schweiz m\u00f6glich.Im Ausland ist der Transport k\u00e4uferseits.<br \/>\n Garantie: 3 Monate Garantie. Bitte beachten Sie, dass die Gew\u00e4hrleistung nur g\u00fcltig ist, wenn der Ersatzteileinbau durch eine Fachwerkstatt\/Meisterwerkstatt erfolgt. Das Ein- und Ausbau des Ersatzteiles kann nicht an uns verrechnet werden. <\/p>\n<p> Ersatzteil: f\u00fcr andere Fahrzeugen (Marken) verf\u00fcgbar auf anfrage. Tel.041 980 27 47. Mobil. 076 589 27 47<\/p>\n<p> Kontakt<br \/>\n  Adresse: Autoverwertung Brun AG<br \/>\n           M\u00f6\u00f6slimatten 13<br \/>\n           6218 Ettiswil<br \/>\n  Telefon: 0041 (041) 980 27 47<br \/>\n  Telefax: 0041 (041) 980 03 47<\/p>\n<p> Wir bieten Ihnen weitere gebrauchte Autoteile zum Kauf an.<br \/>\n Tags: Bremszange Bremssattel hinten, Rear brake caliper, E\u00b4trier de frein arrie`re<br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Technische Daten Fahrzeug: VW Touran 1.4 TSI Chassis Nr.: WVGZZZ1TZ8W076631 Baujahr: 2007 Kilometer: 232169 KM Leistung: 140 KW Hubraum: 1390 ccm Typ: 1VD386 Farbcode: LeichtBraun Hinweise: &#8211; Versand: Versand nur in der Schweiz m\u00f6glich.Im Ausland ist der Transport k\u00e4uferseits. Garantie: 3 Monate Garantie. Bitte beachten Sie, dass die Gew\u00e4hrleistung nur g\u00fcltig ist, wenn der Ersatzteileinbau&hellip; <a class=\"more-link\" href=\"https:\/\/occasions-teile.ch\/en\/produkt\/vw-touran-bremszange-bremssattel-hinten-14\/\">Continue reading <span class=\"screen-reader-text\">VW Touran  Bremszange Bremssattel hinten<\/span><\/a><\/p>\n","protected":false},"featured_media":415837,"template":"","meta":[],"product_brand":[],"product_cat":[779,533,530,777,1086,781,1088,536,1087,2172,2174,2176,1283,1286,1280,25192,25193,25194],"product_tag":[],"class_list":{"0":"post-415840","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-en-brake-calipercarrier","7":"product_cat-en-brake-brake-system","8":"product_cat-de-bremse-bremsanlage","9":"product_cat-de-bremssatteltraeger","10":"product_cat-de-bremszange-bremssattel-hinten","11":"product_cat-fr-etrier-de-frein-support","12":"product_cat-fr-etrier-de-frein-arriere","13":"product_cat-fr-frein-systeme-de-freinage","14":"product_cat-en-rear-brake-caliper","15":"product_cat-de_touran","16":"product_cat-en_touran","17":"product_cat-fr_touran","18":"product_cat-en_volkswagen","19":"product_cat-fr_volkswagen","20":"product_cat-de_volkswagen","21":"product_cat-de-wvgzzz1tz8w076631-200000700","22":"product_cat-en-wvgzzz1tz8w076631-200000700","23":"product_cat-fr-wvgzzz1tz8w076631-200000700","24":"product_shipping_class-tarif-1","25":"entry","27":"first","28":"instock","29":"taxable","30":"shipping-taxable","31":"purchasable","32":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/product\/415840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/media\/415837"}],"wp:attachment":[{"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/media?parent=415840"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/product_brand?post=415840"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/product_cat?post=415840"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/product_tag?post=415840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}