{"id":402782,"date":"2026-05-12T12:10:26","date_gmt":"2026-05-12T12:10:26","guid":{"rendered":"https:\/\/occasions-teile.ch\/product\/vw-polo-drosselklappen-einspritzung-3\/"},"modified":"2026-05-12T12:10:32","modified_gmt":"2026-05-12T12:10:32","slug":"vw-polo-drosselklappen-einspritzung-3","status":"publish","type":"product","link":"https:\/\/occasions-teile.ch\/en\/produkt\/vw-polo-drosselklappen-einspritzung-3\/","title":{"rendered":"VW Polo  Drosselklappen Einspritzung"},"content":{"rendered":"<p><span><b>Technische Daten<\/b><\/p>\n<p> Fahrzeug: VW Polo  9N 1.416V<br \/>\n Chassis Nr.: WVWZZZ9NZ3D137062<br \/>\n Baujahr: 2003<br \/>\n Kilometer: 140046 KM<br \/>\n Leistung: 75 KW<br \/>\n Hubraum: 1390 ccm<br \/>\n Typ: 1VD130<br \/>\n Farbcode: silberblau<br \/>\n Hinweise: &#8211;<\/p>\n<p> Versand: Versand nur in der Schweiz m\u00f6glich.Im Ausland ist der Transport k\u00e4uferseits.<br \/>\n Garantie: 3 Monate Garantie. Bitte beachten Sie, dass die Gew\u00e4hrleistung nur g\u00fcltig ist, wenn der Ersatzteileinbau durch eine Fachwerkstatt\/Meisterwerkstatt erfolgt. Das Ein- und Ausbau des Ersatzteiles kann nicht an uns verrechnet werden. <\/p>\n<p> Ersatzteil: f\u00fcr andere Fahrzeugen (Marken) verf\u00fcgbar auf anfrage. Tel.041 980 27 47. Mobil. 076 589 27 47<\/p>\n<p> Kontakt<br \/>\n  Adresse: Autoverwertung Brun AG<br \/>\n           M\u00f6\u00f6slimatten 13<br \/>\n           6218 Ettiswil<br \/>\n  Telefon: 0041 (041) 980 27 47<br \/>\n  Telefax: 0041 (041) 980 03 47<\/p>\n<p> Wir bieten Ihnen weitere gebrauchte Autoteile zum Kauf an.<br \/>\n Tags: Drosselklappen Einspritzung, Throttle valves\/injection , Vannes a` papillon\/injection<br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Technische Daten Fahrzeug: VW Polo 9N 1.416V Chassis Nr.: WVWZZZ9NZ3D137062 Baujahr: 2003 Kilometer: 140046 KM Leistung: 75 KW Hubraum: 1390 ccm Typ: 1VD130 Farbcode: silberblau Hinweise: &#8211; Versand: Versand nur in der Schweiz m\u00f6glich.Im Ausland ist der Transport k\u00e4uferseits. Garantie: 3 Monate Garantie. Bitte beachten Sie, dass die Gew\u00e4hrleistung nur g\u00fcltig ist, wenn der Ersatzteileinbau&hellip; <a class=\"more-link\" href=\"https:\/\/occasions-teile.ch\/en\/produkt\/vw-polo-drosselklappen-einspritzung-3\/\">Continue reading <span class=\"screen-reader-text\">VW Polo  Drosselklappen Einspritzung<\/span><\/a><\/p>\n","protected":false},"featured_media":402779,"template":"","meta":[],"product_brand":[],"product_cat":[665,1403,663,500,494,497,1636,1638,1634,667,1404,1405,1286,1280,1283,25012,25010,25011],"product_tag":[],"class_list":{"0":"post-402782","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-en-air-fuel-system","7":"product_cat-de-drosselklappen-einspritzung","8":"product_cat-de-luft-kraftstoffsystem","9":"product_cat-fr-moteur","10":"product_cat-de-motor","11":"product_cat-en-motor","12":"product_cat-en_polo","13":"product_cat-fr_polo","14":"product_cat-de_polo","15":"product_cat-fr-systeme-dair-carburant","16":"product_cat-en-throttle-valves-injection","17":"product_cat-fr-vannes-a-papillon-injection","18":"product_cat-fr_volkswagen","19":"product_cat-de_volkswagen","20":"product_cat-en_volkswagen","21":"product_cat-fr-wvwzzz9nz3d137062-200000648","22":"product_cat-de-wvwzzz9nz3d137062-200000648","23":"product_cat-en-wvwzzz9nz3d137062-200000648","24":"product_shipping_class-tarif-1","25":"entry","27":"first","28":"instock","29":"taxable","30":"shipping-taxable","31":"purchasable","32":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/product\/402782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/media\/402779"}],"wp:attachment":[{"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/media?parent=402782"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/product_brand?post=402782"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/product_cat?post=402782"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/occasions-teile.ch\/en\/wp-json\/wp\/v2\/product_tag?post=402782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}